{"id":406,"date":"2026-05-27T17:49:41","date_gmt":"2026-05-27T17:49:41","guid":{"rendered":"https:\/\/fadf.dk\/?page_id=406"},"modified":"2026-05-27T19:13:02","modified_gmt":"2026-05-27T19:13:02","slug":"hjaelper-til-disc","status":"publish","type":"page","link":"https:\/\/fadf.dk\/index.php\/aktiviteter\/disc\/hjaelper-til-disc\/","title":{"rendered":"Hj\u00e6lper til DISC"},"content":{"rendered":"<style id=\"wpforms-css-vars-423-block-86dfd9a0-d2de-41a3-ba8f-bb11702d1e52\">\n\t\t\t\t#wpforms-423.wpforms-block-86dfd9a0-d2de-41a3-ba8f-bb11702d1e52 {\n\t\t\t\t--wpforms-label-color: #ffffff;\n--wpforms-label-sublabel-color: #ffffff;\n--wpforms-field-border-color: #ffffff;\n--wpforms-field-border-color-spare: #ffffff;\n--wpforms-field-text-color: #ffffff;\n--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-block wpforms-block-86dfd9a0-d2de-41a3-ba8f-bb11702d1e52 wpforms-render-modern\" id=\"wpforms-423\"><form id=\"wpforms-form-423\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"423\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/406\" data-token=\"bc37fa14968de98a37b5a9d8ad085a38\" data-token-time=\"1784113263\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\">\t\t<div id=\"wpforms-423-field_3-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"3\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-423-field_3\" >Tirsdag Navn Fredag<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-423-field_3\" class=\"wpforms-field-medium\" name=\"wpforms[fields][3]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-423-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-423-field_1\">Navn <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-423-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" aria-errormessage=\"wpforms-423-field_1-error\" required><\/div><div id=\"wpforms-423-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-423-field_2\">Email <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-423-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" spellcheck=\"false\" aria-errormessage=\"wpforms-423-field_2-error\" required><\/div><div id=\"wpforms-423-field_4-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"4\"><fieldset><legend class=\"wpforms-field-label\">Mandag<\/legend><ul id=\"wpforms-423-field_4\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-423-field_4_1\" name=\"wpforms[fields][4][]\" value=\"Salg af merchandise\" aria-errormessage=\"wpforms-423-field_4_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-423-field_4_1\">Salg af merchandise<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-423-field_4_2\" name=\"wpforms[fields][4][]\" value=\"Oprydning\" aria-errormessage=\"wpforms-423-field_4_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-423-field_4_2\">Oprydning<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-423-field_4_3\" name=\"wpforms[fields][4][]\" value=\"Forplejning\" aria-errormessage=\"wpforms-423-field_4_3-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-423-field_4_3\">Forplejning<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-423-field_4_4\" name=\"wpforms[fields][4][]\" value=\"Eventuelle opgaver\" aria-errormessage=\"wpforms-423-field_4_4-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-423-field_4_4\">Eventuelle opgaver<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-423-field_6-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"6\"><fieldset><legend class=\"wpforms-field-label\">Tirsdag<\/legend><ul id=\"wpforms-423-field_6\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-423-field_6_1\" name=\"wpforms[fields][6][]\" value=\"Salg af merchandise\" aria-errormessage=\"wpforms-423-field_6_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-423-field_6_1\">Salg af merchandise<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-423-field_6_2\" name=\"wpforms[fields][6][]\" value=\"Oprydning\" aria-errormessage=\"wpforms-423-field_6_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-423-field_6_2\">Oprydning<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-423-field_6_3\" name=\"wpforms[fields][6][]\" value=\"Forplejning\" aria-errormessage=\"wpforms-423-field_6_3-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-423-field_6_3\">Forplejning<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-423-field_6_4\" name=\"wpforms[fields][6][]\" value=\"Eventuelle opgaver\" aria-errormessage=\"wpforms-423-field_6_4-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-423-field_6_4\">Eventuelle opgaver<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-423-field_7-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"7\"><fieldset><legend class=\"wpforms-field-label\">Onsdag<\/legend><ul id=\"wpforms-423-field_7\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-423-field_7_1\" name=\"wpforms[fields][7][]\" value=\"Salg af merchandise\" aria-errormessage=\"wpforms-423-field_7_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-423-field_7_1\">Salg af merchandise<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-423-field_7_2\" name=\"wpforms[fields][7][]\" value=\"Oprydning\" aria-errormessage=\"wpforms-423-field_7_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-423-field_7_2\">Oprydning<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-423-field_7_3\" name=\"wpforms[fields][7][]\" value=\"Forplejning\" aria-errormessage=\"wpforms-423-field_7_3-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-423-field_7_3\">Forplejning<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-423-field_7_4\" name=\"wpforms[fields][7][]\" value=\"Eventuelle opgaver\" aria-errormessage=\"wpforms-423-field_7_4-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-423-field_7_4\">Eventuelle opgaver<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-423-field_8-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"8\"><fieldset><legend class=\"wpforms-field-label\">Torsdag<\/legend><ul id=\"wpforms-423-field_8\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-423-field_8_1\" name=\"wpforms[fields][8][]\" value=\"Salg af merchandise\" aria-errormessage=\"wpforms-423-field_8_1-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-423-field_8_1\">Salg af merchandise<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-423-field_8_2\" name=\"wpforms[fields][8][]\" value=\"Oprydning\" aria-errormessage=\"wpforms-423-field_8_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-423-field_8_2\">Oprydning<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-423-field_8_3\" name=\"wpforms[fields][8][]\" value=\"Forplejning\" aria-errormessage=\"wpforms-423-field_8_3-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-423-field_8_3\">Forplejning<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-423-field_8_4\" name=\"wpforms[fields][8][]\" value=\"Eventuelle opgaver\" aria-errormessage=\"wpforms-423-field_8_4-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-423-field_8_4\">Eventuelle opgaver<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-423-field_9-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"9\"><fieldset><legend class=\"wpforms-field-label\">Fredag<\/legend><ul id=\"wpforms-423-field_9\"><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-423-field_9_2\" name=\"wpforms[fields][9][]\" value=\"Oprydning\" aria-errormessage=\"wpforms-423-field_9_2-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-423-field_9_2\">Oprydning<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-423-field_9_4\" name=\"wpforms[fields][9][]\" value=\"Eventuelle opgaver\" aria-errormessage=\"wpforms-423-field_9_4-error\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-423-field_9_4\">Eventuelle opgaver<\/label><\/li><\/ul><\/fieldset><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-423-field_3-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-423-field_3-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-423-field_3-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"423\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/fadf.dk\/index.php\/wp-json\/wp\/v2\/pages\/406\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-423\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Send\" aria-live=\"assertive\" value=\"wpforms-submit\">Send<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fadf.dk\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":325,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"iawp_total_views":3,"inspiro_hide_title":true,"footnotes":""},"class_list":["post-406","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/fadf.dk\/index.php\/wp-json\/wp\/v2\/pages\/406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fadf.dk\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fadf.dk\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fadf.dk\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fadf.dk\/index.php\/wp-json\/wp\/v2\/comments?post=406"}],"version-history":[{"count":12,"href":"https:\/\/fadf.dk\/index.php\/wp-json\/wp\/v2\/pages\/406\/revisions"}],"predecessor-version":[{"id":429,"href":"https:\/\/fadf.dk\/index.php\/wp-json\/wp\/v2\/pages\/406\/revisions\/429"}],"up":[{"embeddable":true,"href":"https:\/\/fadf.dk\/index.php\/wp-json\/wp\/v2\/pages\/325"}],"wp:attachment":[{"href":"https:\/\/fadf.dk\/index.php\/wp-json\/wp\/v2\/media?parent=406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}